{"id":29786,"date":"2026-06-22T08:45:12","date_gmt":"2026-06-22T07:45:12","guid":{"rendered":"https:\/\/www.webtenerife.com\/blogcorporativo\/?p=29786"},"modified":"2026-06-22T08:45:14","modified_gmt":"2026-06-22T07:45:14","slug":"palmares-de-la-i-edicion-de-los-premios-anillos-de-oro","status":"publish","type":"post","link":"https:\/\/www.webtenerife.com\/blogcorporativo\/2026\/06\/palmares-de-la-i-edicion-de-los-premios-anillos-de-oro\/","title":{"rendered":"Palmar\u00e9s de la I edici\u00f3n de los Premios Anillos de Oro"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"500\" src=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2026\/06\/Premios-Anillos-de-Oro-3-880x500.jpg\" alt=\"\" class=\"wp-image-29787\" srcset=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2026\/06\/Premios-Anillos-de-Oro-3-880x500.jpg 880w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2026\/06\/Premios-Anillos-de-Oro-3-300x171.jpg 300w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2026\/06\/Premios-Anillos-de-Oro-3-768x437.jpg 768w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2026\/06\/Premios-Anillos-de-Oro-3.jpg 1024w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><em>La gala, celebrada en el Recinto Ferial de Tenerife, ha sido presentada por Santi Mill\u00e1n y Elena S. S\u00e1nchez, junto al humorista canario Abi\u00e1n D\u00edaz, y las actuaciones musicales de Bel\u00e9n Aguilera, Kiki y Sole\u00e1 Morente, La Bien Querida, Ale Acosta, Las Revoltosas y la Orquesta Filarm\u00f3nica de Tenerife dirigida por Diego Navarro<strong>\u00a0<\/strong><br><\/em><br>La familia de las series espa\u00f1olas se ha reunido en la noche del 20 de junio en\u00a0<strong>Santa Cruz de Tenerife<\/strong>, para celebrar la\u00a0<strong>I edici\u00f3n de los Premios Anillos de Oro.<\/strong>Organizados por el\u00a0<strong>C\u00edrculo de Profesionales de las Series Espa\u00f1olas,<\/strong>\u00a0producidos por\u00a0<strong>Womack Group,<\/strong>\u00a0y contando con el apoyo del\u00a0<strong>Cabildo de Tenerife,<\/strong>\u00a0a trav\u00e9s de Turismo de Tenerife y la Consejer\u00eda insular de Cultura y Museos de Tenerife; el\u00a0<strong>Gobierno de Canarias<\/strong>, a trav\u00e9s de Canary Islands Films y Turismo Islas CanarIas; y el\u00a0<strong>Ayuntamiento de Santa Cruz de Tenerife<\/strong>, a trav\u00e9s de la Sociedad de Desarrollo; siendo<strong>\u00a0Rims Mobility\u00a0<\/strong>e\u00a0<strong>I.C.O.N. Backstage<\/strong>\u00a0sus Sponsor, la\u00a0<strong>I edici\u00f3n de los Premios Anillos de Oro ha entregado\u00a0<\/strong>un total de<strong>\u00a025 estatuillas,<\/strong>\u00a0repartidos entre las 23 categor\u00edas y<strong>\u00a0el Premio de Honor al actor Antonio Resines.<\/strong>La gala de esta primera edici\u00f3n de los Anillos de Oro ha sido presentada por la periodista Elena S. S\u00e1nchez y el actor Santi Mill\u00e1n, que se han subido al escenario del Recinto Ferial de Santa Cruz de Tenerife junto al humorista canario Abi\u00e1n D\u00edaz como monologuista. Adem\u00e1s, la gran \u201cFiesta de las Series\u201d ha contado con las actuaciones musicales de Bel\u00e9n Aguilera, Kiki y Sole\u00e1 Morente, La Bien Querida, Ale Acosta, Las Revoltosas y la Orquesta Filarm\u00f3nica de Tenerife, dirigida por Diego Navarro.<br><br><strong>PALMAR\u00c9S I EDICI\u00d3N PREMIOS ANILLOS DE ORO Premio de Honor<\/strong>Antonio Resines<strong>Mejor guion original<\/strong>Alauda Ru\u00edz de Az\u00faa, Eduard Sola y J\u00falia de Paz por\u00a0<em>Querer<\/em><strong>Mejor guion adaptado<\/strong>Rafael Cobos, Fran Ara\u00fajo y Alberto Rodr\u00edguez por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor edici\u00f3n o montaje<\/strong>Jos\u00e9 M. G. Moyano por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor postproducci\u00f3n y recursos digitales<\/strong>Jos\u00e9 M. G. Moyano por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor serie internacional<\/strong><em>The Walking Dead: Daryl Dixon T.3<\/em><strong>Mejor Film Commission \/ Film Office<\/strong>Ex Aequo:\u00a0<em>Andaluc\u00eda Film Comission\u00a0<\/em>y<em>\u00a0Film Madrid Region<\/em><strong>Mejor serie latinoamericana<\/strong><em>Los mil d\u00edas de Allende<\/em><strong>Mejor int\u00e9rprete de reparto<\/strong>Eduard Fern\u00e1ndez por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor direcci\u00f3n de arte<\/strong>Pepe Dom\u00ednguez del Olmo por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor direcci\u00f3n de producci\u00f3n<\/strong>\u00c1lex Miyata por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor casting<\/strong>Eva Leira y Yolanda Serrano por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor actriz protagonista<\/strong>Carmen Machi por\u00a0<em>Celeste<\/em><strong>Mejor vestuario<\/strong>Helena Sanch\u00eds, con la colaboraci\u00f3n especial de Ana Locking, por\u00a0<em>La vida breve<\/em><strong>Mejor maquillaje y peluquer\u00eda<\/strong>Yolanda Pi\u00f1a y Nacho D\u00edaz por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor fotograf\u00eda<\/strong>\u00c1lex Catal\u00e1n por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor sonido<\/strong>Daniel de Zayas por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor int\u00e9rprete revelaci\u00f3n<\/strong>Carla Qu\u00edlez por\u00a0<em>Yakarta<\/em><strong>Mejor producci\u00f3n ejecutiva<\/strong>Jos\u00e9 Manuel Lorenzo, Manuela Oc\u00f3n Aburto y Fran Ara\u00fajo por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor m\u00fasica<\/strong>C. Tangana por\u00a0<em>Esta ambici\u00f3n desmedida<\/em><strong>Mejor actor protagonista<\/strong>\u00c1lvaro Morte por\u00a0<em>Anatom\u00eda de un instante<\/em><strong>Mejor serie de no ficci\u00f3n<\/strong><em>Esta ambici\u00f3n desmedida<\/em><strong>Mejor serie de ficci\u00f3n comedia<\/strong><em>Poquita Fe<\/em><strong>Mejor serie de ficci\u00f3n dram\u00e1tica<\/strong><em>Anatom\u00eda de un instante<\/em><\/td><\/tr><tr><td>Los&nbsp;<strong>Premios Anillos de Oro 2026,<\/strong>&nbsp;organizados por&nbsp;<strong>C\u00edrculo de Profesionales de las Series Espa\u00f1olas&nbsp;<\/strong>y producidos por&nbsp;<strong>Womack Group,<\/strong>&nbsp;han contado con el apoyo del&nbsp;<strong>Cabildo de Tenerife,<\/strong>&nbsp;a trav\u00e9s de Turismo de Tenerife y la Consejer\u00eda insular de Cultura y Museos de Tenerife; el&nbsp;<strong>Gobierno de Canarias<\/strong>, a trav\u00e9s de Canary Islands Films y Turismo Islas CanarIas; y el&nbsp;<strong>Ayuntamiento de Santa Cruz de Tenerife<\/strong>, a trav\u00e9s de la Sociedad de Desarrollo; siendo&nbsp;<strong>Rims Mobility<\/strong>&nbsp;e&nbsp;<strong>I.C.O.N. Backstage&nbsp;<\/strong>sus Sponsor.<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La gala, celebrada en el Recinto Ferial de Tenerife, ha sido presentada por Santi Mill\u00e1n y Elena S. S\u00e1nchez, junto al humorista canario Abi\u00e1n D\u00edaz, y las actuaciones musicales de Bel\u00e9n Aguilera, Kiki y Sole\u00e1 Morente, La Bien Querida, Ale Acosta, Las Revoltosas y la Orquesta Filarm\u00f3nica de Tenerife dirigida por Diego Navarro\u00a0La familia de [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29786","post","type-post","status-publish","format-standard","hentry","category-destacamos","last_archivepost"],"_links":{"self":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/29786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/comments?post=29786"}],"version-history":[{"count":1,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/29786\/revisions"}],"predecessor-version":[{"id":29789,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/29786\/revisions\/29789"}],"wp:attachment":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media?parent=29786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/categories?post=29786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/tags?post=29786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}