{"id":29655,"date":"2026-05-15T08:14:56","date_gmt":"2026-05-15T07:14:56","guid":{"rendered":"https:\/\/www.webtenerife.com\/blogcorporativo\/?p=29655"},"modified":"2026-05-15T08:14:57","modified_gmt":"2026-05-15T07:14:57","slug":"cita-con-el-hub-gastronomico-trend-talks-turismo-de-tenerife-en-gastrocanarias-2026","status":"publish","type":"post","link":"https:\/\/www.webtenerife.com\/blogcorporativo\/2026\/05\/cita-con-el-hub-gastronomico-trend-talks-turismo-de-tenerife-en-gastrocanarias-2026\/","title":{"rendered":"Cita con el hub gastron\u00f3mico &#8216;Trend Talks Turismo de Tenerife&#8217; en Gastrocanarias 2026"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2026\/05\/GastroCanarias-2025-750x500.jpeg\" alt=\"\" class=\"wp-image-29657\" srcset=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2026\/05\/GastroCanarias-2025-750x500.jpeg 750w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2026\/05\/GastroCanarias-2025-300x200.jpeg 300w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2026\/05\/GastroCanarias-2025-768x512.jpeg 768w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2026\/05\/GastroCanarias-2025.jpeg 1024w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El evento incorpora nuevos espacios de conocimiento, caf\u00e9 de especialidad, formaci\u00f3n y tendencias, reforzando una programaci\u00f3n que combina concursos hist\u00f3ricos, nuevos campeonatos, encuentros con referentes del sector y Galicia como destino invitado<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 11\u00ba Sal\u00f3n Gastron\u00f3mico de Canarias \u2013 GastroCanarias 2026 toca a la puerta con un novedoso programa que acerca el evento al p\u00fablico. Respetando los concursos ya tradicionales e innovando con otros, GastroCanarias 2026 promete no dejar indiferente a nadie con sus numerosas actividades. El evento se celebrar\u00e1 los d\u00edas 19, 20 y 21 de mayo en la Gran Nave del Recinto Ferial de Tenerife.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pistoletazo de salida se dar\u00e1 el martes 19 de mayo con la inauguraci\u00f3n oficial por parte de las principales autoridades y patrocinadores. Tras este se celebrar\u00e1 el plato fuerte del sal\u00f3n: el 20\u00ba Campeonato de Canarias de Cocina 2026 Gran Premio Cepsa, en el Escenario Cabildo de Tenerife. En el mismo lugar se celebrar\u00e1, en horario vespertino, el 19\u00ba Campeonato de Canarias de J\u00f3venes Cocineros Gran Premio Binter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el escenario Cabildo de Tenerife tambi\u00e9n se celebrar\u00e1n, el mi\u00e9rcoles y el jueves, los concursos de Bocadillos Canarios de Autor Gran Premio Fred Olsen; Ensaladillas Gran Premio Hellman\u2019s; Tapas Gran Premio Makro; Tostas de Desayuno Gran Premio Europastry; Panader\u00eda Artesana Gran Premio Haricana y Pasteler\u00eda Gran Premio Harinalia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por primera vez, Galicia ser\u00e1 el destino invitado de GastroCanarias 2026, reforzando el car\u00e1cter abierto, atl\u00e1ntico y profesional del Sal\u00f3n. Su presencia permitir\u00e1 tender puentes entre dos territorios con una profunda identidad gastron\u00f3mica, vinculados al producto, al mar, al paisaje y a una cocina con ra\u00edz. A trav\u00e9s de distintas acciones dentro del programa, Galicia compartir\u00e1 con el p\u00fablico profesional su riqueza culinaria, su despensa, sus modelos de promoci\u00f3n gastron\u00f3mica y la fuerza de una cultura alimentaria que dialoga de manera natural con Canarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Escenario Heineken<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las novedades del XI Sal\u00f3n Gastron\u00f3mico de Canarias \u2013 GastroCanarias 2026 reside en el Escenario Heineken, en el que los Hub Gastron\u00f3micos Trend Talks ser\u00e1n los protagonistas de las ma\u00f1anas con ponencias, mesas redondas y entrevistas con chefs, expertos y referentes del sector para hablar de tendencias, hospitality, rentabilidad,&nbsp; gesti\u00f3n, pasteler\u00eda, producto, vino, sala, branding y futuro gastron\u00f3mico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El d\u00eda19 se inaugura el Hub Gastron\u00f3mico Trend Talks Turismo de Tenerife, que arrancar\u00e1 con la bienvenida de la CEO de Turismo de Tenerife, Dimple Melwani. Posteriormente, Carlos Gamonal abrir\u00e1 el turno de ponencias con el t\u00edtulo \u201cC\u00f3mo sostener un restaurante familiar en el siglo XXI\u00bb. Marcas con sentido: c\u00f3mo contar y hacer crecer tu proyecto gastron\u00f3mico, por Aliter Dulcia. Tambi\u00e9n destacan la mesa \u201cComer tambi\u00e9n cura: la gastronom\u00eda como herramienta de salud\u201d, con la participaci\u00f3n de Xandra Luque, jefa de cocina de Cl\u00ednica Universidad de Navarra, Braulio Simancas y Sergio Mart\u00edn; la presentaci\u00f3n oficial de la Gu\u00eda Macarfi en Canarias y la revoluci\u00f3n femenina de la pasteler\u00eda y los asadores contempor\u00e1neos. En horario de tarde, el escenario Heineken ser\u00e1 el lugar donde se celebre el 7\u00ba Campeonato de Canarias de pizzas Gran Premio Comit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Hub Gastron\u00f3mico Trends talks, contin\u00faa en el Escenario Heineken el mi\u00e9rcoles 20 de la mano de Volcanic Xperience y contar\u00e1 con bienvenida de Juan Antonio Alonso, consejero delegado de GMR Canarias. La jornada estar\u00e1 repleta de ponencias: enogastroturismo; la mesa \u201cWoman Wine\u201d que pone el foco en el relevo generacional femenino en el mundo del vino. Una de las mesas m\u00e1s destacadas ser\u00e1 la del pastelero madrile\u00f1o Ricardo V\u00e9lez y la historia de c\u00f3mo se cre\u00f3 la mejor palmera de chocolate del mundo. Una mesa sobre el movimiento Slowfood y otra de Hacia d\u00f3nde debe mirar la cocina canaria con Jos\u00e9 Carlos Capel, Jes\u00fas Gonz\u00e1lez y Rigoberto Almeida, prometen. La sala toma el mando en la mesa protagonizada por Aida Gonz\u00e1lez (Gofio), Rafael Hurtado (Poemas) y Roberto Castro (Secreto de Chimiche). Cerrando las ponencias de este d\u00eda, la presentaci\u00f3n de la ponencia: Del campo al plato: la nueva mirada gastron\u00f3mica de la ganader\u00eda canaria.&nbsp; Y a continuaci\u00f3n el 2\u00ba campeonato de montaje de mesas Gran Premio Adom: la mesa como experiencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00faltimo d\u00eda estar\u00e1 dedicado al bloque profesional vinculado a HECANSA, centrado en la formaci\u00f3n, hoteler\u00eda, hosteler\u00eda, negocio, tecnolog\u00eda y nuevos perfiles profesionales. La jornada comenzar\u00e1 con la presentaci\u00f3n de la nueva oferta educativa de HECANSA a cargo de su consejera delegada, Paola Plasencia. El plato fuerte de la jornada ser\u00e1 la mesa redonda \u201cM\u00e1s all\u00e1 del plato: dise\u00f1ar, conceptualizar y rentabilizar un proyecto gastron\u00f3mico\u201d, con Javier Bonet, director creativo y chef-emprendedor; Iv\u00e1n Merino, dise\u00f1ador industrial especializado en Food Design; y Vanessa Zamora, interiorista especializada en hoteles, espacios profesionales y arquitecturas ef\u00edmeras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mesa sobre la formaci\u00f3n de perfiles h\u00edbridos para la hosteler\u00eda que viene; el cada vez mayor valor del desayuno en los hoteles, la inteligencia artificial o el marketing gastron\u00f3mico, prometen una jornada llena de herramientas para los profesionales de la hosteler\u00eda porque solo cocinar, ya no basta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Espacio La Marzocco<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Espacio La Marzocco ser\u00e1 el lugar del I Campeonato de Baristas de Canarias, una de las grandes novedades de la XI edici\u00f3n del Sal\u00f3n Gastron\u00f3mico de Canarias \u2013 GastroCanarias 2026. El concurso contar\u00e1 con la colaboraci\u00f3n de El Caf\u00e9 de Don Manuel, proyecto impulsado por el tostador palmero Rayco Paz, referente en el \u00e1mbito del caf\u00e9 de especialidad en Canarias y a nivel internacional. Adem\u00e1s, el caf\u00e9 tostado por El Caf\u00e9 de Don Manuel ser\u00e1 el que utilicen todos los participantes en sus diferentes elaboraciones, convirti\u00e9ndose en una pieza fundamental para el desarrollo t\u00e9cnico y sensorial del campeonato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El espacio acoger\u00e1 ponencias vinculadas a cafeter\u00edas y proyectos participantes en el entorno del campeonato adem\u00e1s de sesiones dedicadas a proyectos cafeteros de referencia y un \u00faltimo d\u00eda que estar\u00e1 especialmente centrada en productores y tostadores de caf\u00e9, poniendo el foco en el origen, el cultivo, el tueste y la cadena de valor del caf\u00e9 en Canarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aula Makro<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Aula Makro destacar\u00e1 un a\u00f1o m\u00e1s el compromiso de Makro con la formaci\u00f3n. En el espacio se llevar\u00e1n a cabo numerosos talleres desde el primer d\u00eda que abarcan desde postres tradicionales, bebidas naturales, cocina a la brasa y alimentos primigenios hasta valorizar la alta cocina canaria. Profesionales de la talla de: Carlos Maldonado, Yolanda Le\u00f3n y Juanjo P\u00e9rez, Jenisse Ferrari, Rub\u00e9n Cuesta, Iv\u00e1n Sancho, Manuel Franco, V\u00edctor Su\u00e1rez, Luc\u00eda Gr\u00e1valos o Eduardo Dom\u00ednguez impartir\u00e1n talleres y compartir\u00e1n conocimiento y experiencia en un Aula que siempre se queda peque\u00f1a debido a la alta demanda de asistencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GastroCanarias 2026<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El XI Sal\u00f3n Gastron\u00f3mico de Canarias \u2013 GastroCanarias 2026 se celebrar\u00e1 del 19 al 21 de mayo en la Gran Nave del Recinto Ferial de Tenerife, consolidado como uno de los principales encuentros profesionales del sector gastron\u00f3mico, hostelero y alimentario de Canarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Sal\u00f3n Gastron\u00f3mico de Canarias cuenta con la organizaci\u00f3n del Recinto Ferial de Tenerife y GastroCanarias, con la colaboraci\u00f3n institucional del Cabildo de Tenerife, Gobierno de Canarias y Ayuntamiento de Santa Cruz de Tenerife; el patrocinio principal de Heineken y Cajasiete; y la colaboraci\u00f3n de Volcanic Xperience, Tenerife Despierta Emociones, Hecansa, Makro, Harinalia, Cepsa, Grupo Comit, Haricana, Fred. Olsen Express, Binter, Europastry, Hellmann\u2019s, El Corte Ingl\u00e9s, Nespresso, Royal Bliss, Acqua Panna; San Pellegrino; La Marzocco, El Caf\u00e9 de Don Manuel, Hoalve, Sammic, Chafiras, Electrodom\u00e9sticos Balay, Barcel\u00f3 Santa Cruz Contempor\u00e1neo, Cointeca, Fiat, Adom, Canarias Cocina, Titsa y Thermomix<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento incorpora nuevos espacios de conocimiento, caf\u00e9 de especialidad, formaci\u00f3n y tendencias, reforzando una programaci\u00f3n que combina concursos hist\u00f3ricos, nuevos campeonatos, encuentros con referentes del sector y Galicia como destino invitado El 11\u00ba Sal\u00f3n Gastron\u00f3mico de Canarias \u2013 GastroCanarias 2026 toca a la puerta con un novedoso programa que acerca el evento al p\u00fablico. [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":29658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacamos","last_archivepost"],"_links":{"self":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/29655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/comments?post=29655"}],"version-history":[{"count":2,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/29655\/revisions"}],"predecessor-version":[{"id":29659,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/29655\/revisions\/29659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media\/29658"}],"wp:attachment":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media?parent=29655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/categories?post=29655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/tags?post=29655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}