{"id":21830,"date":"2019-12-02T14:01:28","date_gmt":"2019-12-02T13:01:28","guid":{"rendered":"https:\/\/www.webtenerife.com\/blogcorporativo\/?p=21830"},"modified":"2019-12-02T14:46:03","modified_gmt":"2019-12-02T13:46:03","slug":"se-instaura-la-ley-seca-en-tenerife-con-el-espectaculo-la-gastronomia-y-los-vinos-de-bodegas-monje","status":"publish","type":"post","link":"https:\/\/www.webtenerife.com\/blogcorporativo\/2019\/12\/se-instaura-la-ley-seca-en-tenerife-con-el-espectaculo-la-gastronomia-y-los-vinos-de-bodegas-monje\/","title":{"rendered":"Se instaura la ley seca con el espect\u00e1culo, la gastronom\u00eda y los vinos de Bodegas Monje"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El establecimiento de El Sauzal habilita un \u2018speakeasy\u2019 para escanciar de forma ilegal sus variedades y burlar la estrecha vigilancia policial <\/p>\n\n\n\n<!--more-->\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"695\" src=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/06\/P1110625.jpg\" alt=\"\" class=\"wp-image-18360\" srcset=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/06\/P1110625.jpg 984w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/06\/P1110625-300x212.jpg 300w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/06\/P1110625-768x542.jpg 768w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/06\/P1110625-708x500.jpg 708w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/06\/P1110625-600x424.jpg 600w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/><figcaption>Aspecto del restaurante de Bodegas Monje, en el municipio de El Sauzal<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/bodegasmonje.com\/\">Bodegas Monje<\/a> a\u00fana espect\u00e1culo, cultura, gastronom\u00eda y vinos, en un nuevo proyecto que se repetir\u00e1 de forma continua cada quince d\u00edas, una nueva apuesta de la conocida marca bodeguera de El Sauzal por la innovaci\u00f3n y la diferenciaci\u00f3n de un mercado que cada vez exige nuevas experiencias. Lo cierto, es que, seg\u00fan fuentes fidedignas de soplones convenientemente sobornados, la polic\u00eda investiga la apertura en el establecimiento norte\u00f1o nada menos que de un aut\u00e9ntico \u2018speakeasy\u2019, que es como denominaban los estadounidenses en la Ley Seca a los tugurio escondidos para escapar a la vigilancia de las autoridades. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/12\/Monje.jpg\" alt=\"\" class=\"wp-image-21841\" width=\"400\" height=\"480\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado domingo 17 de noviembre fue abierto en el Club del Vino de Bodegas Monje, y de forma \u00abclandestina\u00bb, un tugurio donde poder hacer acopio de una selecci\u00f3n de los mejores vinos de la bodega, as\u00ed como disfrutar de un aut\u00e9ntico espect\u00e1culo bajo la tem\u00e1tica de la Ley Seca de Estados Unidos en los a\u00f1os 20&#8217;s. Eso s\u00ed, actualmente estos peque\u00f1os bares y sus mafias est\u00e1n siendo investigados por la polic\u00eda y se va estrechando el cerco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este simp\u00e1tica apuesta que ha ideado Bodegas Monje, el p\u00fablico asistente puede disfrutar a lo largo de una tres horas de los vinos y platos en el Club del Vino, mientras vive el ambiente de un &#8216;speakeasy&#8217; con una \u00abilegal y divertida\u00bb obra teatral, despu\u00e9s de realizar una visita guiada a las bodegas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El espect\u00e1culo est\u00e1 a cargo de <a href=\"http:\/\/jasterluis.com\/\">Jaster &amp; Luis Creaciones<\/a>, mientras que la cocina, obra del chef del restaurante de la bodega, Mois\u00e9s Rodr\u00edguez, se compone de un men\u00fa especial para maridar a la perfecci\u00f3n con los mejores vinos de la bodega. As\u00ed, la elecci\u00f3n para el Dragoblanco 2018, ser\u00e1n los aperitivos para untar y ensalada de flores; para el Tinto Monje Tradicional 2017, brocheta de pescado con papa de color y mojo azafr\u00e1n; el Monje List\u00e1n Negro 2014, en compa\u00f1\u00eda de mini hamburguesa con guarnici\u00f3n; llegando al postre New York Cheesecake, con el Monje Moscatel 2017.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toda la informaci\u00f3n est\u00e1 disponible en <a href=\"https:\/\/bodegasmonje.com\/\">bodegasmonje.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redes sociales: <a href=\"https:\/\/www.facebook.com\/BodegasMonje\/\"> https:\/\/www.facebook.com\/BodegasMonje\/<\/a><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Contacto: <strong>Felipe Monje<\/strong> 922 585 027<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El establecimiento de El Sauzal habilita un \u2018speakeasy\u2019 para escanciar de forma ilegal sus variedades y burlar la estrecha vigilancia policial<\/p>\n","protected":false},"author":1,"featured_media":21839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2649,2184,20],"class_list":["post-21830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacamos","tag-el-sauzal","tag-enologia","tag-gastronomia","last_archivepost"],"_links":{"self":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/21830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/comments?post=21830"}],"version-history":[{"count":5,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/21830\/revisions"}],"predecessor-version":[{"id":21856,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/21830\/revisions\/21856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media\/21839"}],"wp:attachment":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media?parent=21830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/categories?post=21830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/tags?post=21830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}