{"id":16715,"date":"2019-03-29T12:53:27","date_gmt":"2019-03-29T11:53:27","guid":{"rendered":"https:\/\/www.webtenerife.com\/blogcorporativo\/?p=16715"},"modified":"2019-05-11T13:33:13","modified_gmt":"2019-05-11T12:33:13","slug":"the-travel-foundation-publica-un-informe-sobre-las-cargas-invisibles-del-turismo","status":"publish","type":"post","link":"https:\/\/www.webtenerife.com\/blogcorporativo\/2019\/03\/the-travel-foundation-publica-un-informe-sobre-las-cargas-invisibles-del-turismo\/","title":{"rendered":"The Travel Foundation publica un informe sobre las cargas invisibles del turismo"},"content":{"rendered":"<p><em>A este concepto aplicado a la Isla se refiri\u00f3 Alberto Bernab\u00e9 en la \u00faltima edici\u00f3n de la ITB de Berl\u00edn<\/em><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16718 size-full aligncenter\" src=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/Portada.jpg\" alt=\"\" width=\"656\" height=\"984\" srcset=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/Portada.jpg 656w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/Portada-200x300.jpg 200w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/Portada-333x500.jpg 333w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/Portada-600x900.jpg 600w\" sizes=\"auto, (max-width: 656px) 100vw, 656px\" \/>The <a href=\"https:\/\/www.thetravelfoundation.org.uk\/\">Travel Foundation<\/a>, plataforma brit\u00e1nica independiente que trabaja en asociaci\u00f3n con empresas y gobiernos para que el turismo aporte mayores beneficios para las personas y el medio ambiente, acaba de publicar <a href=\"https:\/\/www.webtenerife.com\/es\/asociados\/informes\/documents\/invisible-burden-report.pdf?userId=UwMNlZpiejTTeKRh7Rh7oM0iqlxneamO2hdS5OdaMaY29cn\/e5j\/ikvfRsuz8sZG\">un informe<\/a> sobre las cargas invisibles de la actividad.<\/p>\n<p>El documento, que analiza sustancialmente en sus p\u00e1ginas aspectos relacionados con este concepto cada vez m\u00e1s extendido en el sector a nivel internacional, tiene como antesala <a href=\"https:\/\/www.webtenerife.com\/blogcorporativo\/2019\/03\/alberto-bernabe-resalta-en-la-itb-los-beneficios-del-turismo-para-la-isla.html\">un coloquio celebrado en la \u00faltima edici\u00f3n de la ITB<\/a> de Berl\u00edn en el que particip\u00f3 el vicepresidente y consejero de Turismo del Cabildo de Tenerife, Alberto Bernab\u00e9, quien ya se refer\u00eda a esas cargas invisibles en la Isla en base a tres desaf\u00edos: como financiar el turismo y el debate de la denominada tasa tur\u00edstica; la movilidad y sobrecarga en las carreteras, influidas tambi\u00e9n por el turismo, y la gesti\u00f3n de los espacios tur\u00edsticos sensibles.<\/p>\n<p><iframe loading=\"lazy\" title=\"Tourism&#039;s Invisible Burden\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ON_wVykiVL0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A este concepto aplicado a la Isla se refiri\u00f3 Alberto Bernab\u00e9 en la \u00faltima edici\u00f3n de la ITB de Berl\u00edn<\/p>\n","protected":false},"author":18,"featured_media":17572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2012,1799,122,2011,586],"class_list":["post-16715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacamos","tag-cargas-ocultas","tag-informe","tag-tenerife","tag-travel-foundation","tag-turismo","last_archivepost"],"_links":{"self":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/16715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/comments?post=16715"}],"version-history":[{"count":5,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/16715\/revisions"}],"predecessor-version":[{"id":16725,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/16715\/revisions\/16725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media\/17572"}],"wp:attachment":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media?parent=16715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/categories?post=16715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/tags?post=16715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}