{"id":16693,"date":"2019-03-08T15:52:17","date_gmt":"2019-03-08T14:52:17","guid":{"rendered":"https:\/\/www.webtenerife.com\/blogcorporativo\/?p=16693"},"modified":"2019-03-28T15:54:14","modified_gmt":"2019-03-28T14:54:14","slug":"alberto-bernabe-resalta-en-la-itb-los-beneficios-del-turismo-para-la-isla","status":"publish","type":"post","link":"https:\/\/www.webtenerife.com\/blogcorporativo\/2019\/03\/alberto-bernabe-resalta-en-la-itb-los-beneficios-del-turismo-para-la-isla\/","title":{"rendered":"Alberto Bernab\u00e9 resalta en la ITB  los beneficios del turismo para la Isla"},"content":{"rendered":"<p><em>El consejero insular de Turismo participa en la feria en un debate organizado por \u2018The Travel Foundation\u2019 sobre el impacto de la industria tur\u00edstica en los destinos<\/em><!--more--><\/p>\n<p><a href=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/ITB-Debate-turistico-02.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16694\" src=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/ITB-Debate-turistico-02.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/ITB-Debate-turistico-02.jpg 1600w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/ITB-Debate-turistico-02-300x225.jpg 300w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/ITB-Debate-turistico-02-768x576.jpg 768w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/ITB-Debate-turistico-02-667x500.jpg 667w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/03\/ITB-Debate-turistico-02-600x450.jpg 600w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a>El vicepresidente del Cabildo y consejero insular de Turismo, Alberto Bernab\u00e9, ha resaltado esta ma\u00f1ana los beneficios de la actividad tur\u00edstica para la Isla en un debate organizado por <em>The Travel Foundation<\/em> en el marco de la ITB. La sesi\u00f3n se ha centrado en los impactos del turismo en los destinos y en c\u00f3mo las administraciones p\u00fablicas pueden gestionarlos mejor para obtener los m\u00e1ximos beneficios de este.<\/p>\n<p>La intervenci\u00f3n del consejero se ha centrado en cuatro aspectos sobre los que interviene la actividad tur\u00edstica, como son el territorio, el agua, la energ\u00eda y los residuos. A la vez, se ha referido a los ingresos del turismo, que el a\u00f1o pasado ascendieron a unos 4.300 millones de euros para Tenerife y que, posteriormente, se invierten en el desarrollo de las infraestructuras de la Isla, en atender los m\u00faltiples servicios que demandan los tinerfe\u00f1os, etc. \u201cM\u00e1s all\u00e1 de los ingresos, entre los beneficios del turismo para Tenerife se encuentran la diversidad de oportunidades de empleo, la influencia en el desarrollo de otros sectores de la econom\u00eda, un mayor acceso a diferentes productos, la mejora del bienestar de la poblaci\u00f3n local o la contribuci\u00f3n a una mejor conservaci\u00f3n del patrimonio cultural\u201d, explica Bernab\u00e9.<\/p>\n<p>El consejero tambi\u00e9n se ha referido durante el debate a las denominadas \u2018cargas invisibles\u2019. Para Alberto Bernab\u00e9 el turismo se enfrenta a tres desaf\u00edos en el caso de Tenerife: por un lado,\u00a0 como financiar el turismo y el debate de la denominada \u2018tasa tur\u00edstica\u2019; la movilidad y sobrecarga en las carreteras influidas\u00a0 tambi\u00e9n\u00a0 por el turismo y la gesti\u00f3n de los espacios tur\u00edsticos sensibles como Teno, Masca o el propio Parque Nacional del Teide, \u201cque requieren de una gesti\u00f3n espec\u00edfica por parte de las autoridades p\u00fablicas\u201d.<\/p>\n<p>La sesi\u00f3n, titulada <em>Destinos en la balanza: conseguir el equilibro para visitantes y residentes, <\/em>se celebra en el denominado <em>Destinations Day<\/em> de la ITB<em>. <\/em>En el debate en el que ha participado Bernab\u00e9 han estado tambi\u00e9n presentes Megan Epler, directora del Programa de Turismo Sostenible de la Universidad de Cornell (Nueva York, EEUU) y Sofia Fotiadou, responsable de Investigaci\u00f3n de la Iniciativa de Turismo Sostenible del Harvard Chan School of Public Health, perteneciente a la Universidad de Harvard (Boston, EEUU).<\/p>\n<p><strong>An\u00e1lisis de Tenerife<\/strong><\/p>\n<p>El consejero recuerda que Tenerife es uno de los destinos que la Universidad de Cornell y <em>The Travel Foundation<\/em> est\u00e1n analizando para determinar cu\u00e1les son las cargas que soporta la Isla. \u201cEl an\u00e1lisis incluye los beneficios y los costes del turismo procedente de nuestros principales mercados, a la vez que provee de claves acerca del valor que aporta cada uno al destino. En \u00faltima instancia, propone medidas para conseguir el mejor impacto posible\u201d, se\u00f1ala.<\/p>\n<p>En el an\u00e1lisis, que a\u00fan est\u00e1 siendo llevado a cabo, se est\u00e1n teniendo en cuenta aspectos como la edad, nacionalidad, estructura familiar o n\u00famero de visitantes a la Isla, adem\u00e1s de su nivel de gasto, actividades que realizan durante su estancia o nivel de satisfacci\u00f3n. Tras una segunda fase en la que se recopilar\u00e1 informaci\u00f3n del sector privado y entidades p\u00fablicas relacionadas con el turismo, el informe final estar\u00e1 terminado en verano.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El consejero insular de Turismo participa en la feria en un debate organizado por \u2018The Travel Foundation\u2019 sobre el impacto de la industria tur\u00edstica en los destinos<\/p>\n","protected":false},"author":18,"featured_media":16694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[663,252,586],"class_list":["post-16693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacamos","tag-debate","tag-itb","tag-turismo","last_archivepost"],"_links":{"self":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/16693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/comments?post=16693"}],"version-history":[{"count":1,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/16693\/revisions"}],"predecessor-version":[{"id":16695,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/16693\/revisions\/16695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media\/16694"}],"wp:attachment":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media?parent=16693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/categories?post=16693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/tags?post=16693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}