{"id":15901,"date":"2019-01-24T11:47:11","date_gmt":"2019-01-24T10:47:11","guid":{"rendered":"https:\/\/www.webtenerife.com\/blogcorporativo\/?p=15901"},"modified":"2019-01-28T13:40:48","modified_gmt":"2019-01-28T12:40:48","slug":"tenerife-sera-el-escenario-de-los-xiii-premios-cadena-dial","status":"publish","type":"post","link":"https:\/\/www.webtenerife.com\/blogcorporativo\/2019\/01\/tenerife-sera-el-escenario-de-los-xiii-premios-cadena-dial\/","title":{"rendered":"Tenerife ser\u00e1 el escenario de los XIII Premios Cadena Dial"},"content":{"rendered":"<p><em>La gala de entrega de esta edici\u00f3n de los Premios Cadena Dial tendr\u00e1 lugar el 14 de marzo en la Isla<\/em><!--more--><\/p>\n<p><a href=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/01\/Cadena-DIAL-2019.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15890\" src=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/01\/Cadena-DIAL-2019.png\" alt=\"\" width=\"957\" height=\"608\" srcset=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/01\/Cadena-DIAL-2019.png 957w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/01\/Cadena-DIAL-2019-300x191.png 300w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/01\/Cadena-DIAL-2019-768x488.png 768w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/01\/Cadena-DIAL-2019-787x500.png 787w, https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2019\/01\/Cadena-DIAL-2019-600x381.png 600w\" sizes=\"auto, (max-width: 957px) 100vw, 957px\" \/><\/a>Tenerife vuelve a ser el escenario elegido para una de las citas musicales m\u00e1s importantes del a\u00f1o,\u00a0la gala de entrega de los XIII Premios Cadena Dial, que este a\u00f1o premiar\u00e1 a David Bisbal, Vanesa Mart\u00edn, Blas Cant\u00f3, Laura Pausini, Melendi, Cepeda, Pablo Albor\u00e1n, Morat, Reik, Miriam Rodr\u00edguez, Marta Soto, Manuel Carrasco, Carlos Rivera y Adexe y Nau.<\/p>\n<p>Los premios especiales por su trayectoria y aportaci\u00f3n\u00a0 al pop espa\u00f1ol ser\u00e1n para Mal\u00fa, por sus 20 a\u00f1os en el mundo de la m\u00fasica, y el cantautor canario Pedro Guerra, que celebra el 25 aniversario de la publicaci\u00f3n de su \u00e1lbum \u2018Golosinas\u2019. La gala tambi\u00e9n contar\u00e1 con las actuaciones de Bustamante, Carlos Baute y Marta S\u00e1nchez, Funambulista, Diego Torres y Sebasti\u00e1n Yatra.<\/p>\n<p>La gran expectaci\u00f3n y acogida de este evento que lleva celebr\u00e1ndose varios a\u00f1os en Tenerife ha quedado constatada una vez m\u00e1s al agotarse las entradas en tan solo dos horas despu\u00e9s de ponerse a la venta y sin conocerse el cartel de artistas, lo que \u00abdemuestra la vinculaci\u00f3n de los #PremiosDial con Tenerife\u201d, tal y como se\u00f1al\u00f3 Carlos Alonso en el acto informativo que tuvo lugar ayer en Madrid.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gala de entrega de esta edici\u00f3n de los Premios Cadena Dial tendr\u00e1 lugar el 14 de marzo en la Isla<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1928,122],"class_list":["post-15901","post","type-post","status-publish","format-standard","hentry","category-destacamos","tag-premiso-cadena-dial","tag-tenerife","last_archivepost"],"_links":{"self":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/15901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/comments?post=15901"}],"version-history":[{"count":2,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/15901\/revisions"}],"predecessor-version":[{"id":15910,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/15901\/revisions\/15910"}],"wp:attachment":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media?parent=15901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/categories?post=15901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/tags?post=15901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}