{"id":14796,"date":"2018-05-21T10:24:58","date_gmt":"2018-05-21T09:24:58","guid":{"rendered":"https:\/\/www.webtenerife.com\/blogcorporativo\/?p=14796"},"modified":"2018-05-21T10:24:58","modified_gmt":"2018-05-21T09:24:58","slug":"la-isla-se-promociona-como-destino-de-congresos-y-eventos-en-la-feria-imex-de-francfort","status":"publish","type":"post","link":"https:\/\/www.webtenerife.com\/blogcorporativo\/2018\/05\/la-isla-se-promociona-como-destino-de-congresos-y-eventos-en-la-feria-imex-de-francfort\/","title":{"rendered":"La Isla se promociona como destino de congresos y eventos en la feria IMEX de Fr\u00e1ncfort"},"content":{"rendered":"<p><em>Tenerife Convention Bureau ha asistido a la cita junto a varias empresas asociadas a Turismo de Tenerife<\/em><!--more--><\/p>\n<p><a href=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2018\/05\/TCB-Feria-IMEX.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14798\" src=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2018\/05\/TCB-Feria-IMEX-500x281.jpg\" alt=\"\" width=\"500\" height=\"281\" \/><\/a>Turismo de Tenerife, a trav\u00e9s de Tenerife Convention Bureau (TCB), ha asistido esta semana a la feria IMEX, celebrada en la ciudad alemana de Fr\u00e1ncfort. Dirigida a organizadores de eventos, empresas, viajes de negocios y profesionales de la mercadotecnia, es el encuentro m\u00e1s importante para congresos y viajes de incentivos en Alemania.<\/p>\n<p>El consejero insular de Turismo, Alberto Bernab\u00e9, explica que \u201cTenerife se ha convertido en los \u00faltimos a\u00f1os en un relevante destino en este \u00e1mbito tanto a nivel nacional como internacional\u201d. Seg\u00fan explica el consejero, \u201cel sector de congresos ingresa al a\u00f1o unos 100 millones de euros en Tenerife en las aproximadamente 800 convenciones y eventos que se celebran en la Isla con una participaci\u00f3n estimada de 45.000 personas\u201d.<\/p>\n<p>Tenerife re\u00fane unas condiciones inmejorables para acoger toda clase de congresos, eventos, presentaciones de productos y viajes de incentivo. Entre sus argumentos se encuentran una temperatura media anual de 23 grados cent\u00edgrados, modernos y llamativos centros de congresos, completamente adaptables en su interior y con capacidad para hasta 4.000 personas, o una oferta de hoteles de 4 y 5 estrellas entre los mejores de Europa. A ello hay que a\u00f1adir unos establecimientos que cuentan asimismo con multitud de salas y espacios para celebrar reuniones y acoger cualquier tipo de evento independientemente de su n\u00famero de asistentes o de sus necesidades espaciales y t\u00e9cnicas.<\/p>\n<p><a href=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2018\/05\/TCB-Feria-IMEX-01-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14799\" src=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2018\/05\/TCB-Feria-IMEX-01-1-467x350.jpg\" alt=\"\" width=\"467\" height=\"350\" \/><\/a>Integrados en el stand de Promotur-Gobierno de Canarias, los t\u00e9cnicos de Tenerife Convention Bureau presentes en la feria han mantenido m\u00e1s de una veintena de reuniones, a las que hay que sumar las celebradas por las siete empresas de la Isla asociadas a la marca de Turismo de Tenerife (hoteles y agencias locales organizadoras de eventos), y que rondan en conjunto el centenar de encuentros profesionales.<\/p>\n<p>El TCB ha realizado adem\u00e1s presentaciones del destino y sus novedades \u2014en especial nuevos establecimientos enfocados a congresos y eventos\u2014 a unos 50 asistentes a la feria, entre ellos agencias de viajes especializadas en la organizaci\u00f3n de eventos, congresos, presentaciones de productos y viajes de incentivos.<\/p>\n<p><strong>Tenerife Convention Bureau<\/strong><\/p>\n<p>Tenerife Convention Bureau proporciona toda la informaci\u00f3n necesaria a los promotores de congresos y agencias organizadoras de eventos con rapidez, eficacia y profesionalidad, y sirve de enlace con los proveedores de servicio locales y con los organismos oficiales de Tenerife.\u00a0 El TCB agrupa un amplio abanico de empresas, un total de 70, entre palacios o centros de congresos, hoteles, compa\u00f1\u00edas de transportes, azafatas, comunicaci\u00f3n, catering, traducci\u00f3n simult\u00e1nea, equipamiento audiovisual, agencias de viajes receptivas y OPCs o instalaciones de ocio.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tenerife Convention Bureau ha asistido a la cita junto a varias empresas asociadas a Turismo de Tenerife<\/p>\n","protected":false},"author":18,"featured_media":14798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[136,965,772,83,29],"class_list":["post-14796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacamos","tag-congresos","tag-francfort","tag-imex","tag-tcb","tag-tenerife-convention-bureau","last_archivepost"],"_links":{"self":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/14796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/comments?post=14796"}],"version-history":[{"count":1,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/14796\/revisions"}],"predecessor-version":[{"id":14800,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/14796\/revisions\/14800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media\/14798"}],"wp:attachment":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media?parent=14796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/categories?post=14796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/tags?post=14796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}