{"id":14697,"date":"2018-05-14T09:45:05","date_gmt":"2018-05-14T08:45:05","guid":{"rendered":"https:\/\/www.webtenerife.com\/blogcorporativo\/?p=14697"},"modified":"2018-05-14T09:45:05","modified_gmt":"2018-05-14T08:45:05","slug":"vuelve-fenautica","status":"publish","type":"post","link":"https:\/\/www.webtenerife.com\/blogcorporativo\/2018\/05\/vuelve-fenautica\/","title":{"rendered":"Vuelve Fen\u00e1utica"},"content":{"rendered":"<p><em>Ya tenemos a la vuelta de la esquina una nueva edici\u00f3n de Fen\u00e1utica, que se celebrar\u00e1 el primer fin de semana de junio en Marina del Sur, el puerto de Las Galletas<\/em><!--more--><br \/>\n<a href=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2018\/05\/fenautica2018_A4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-14711\" src=\"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-content\/uploads\/2018\/05\/fenautica2018_A4-248x350.jpg\" alt=\"\" width=\"248\" height=\"350\" \/><\/a>Ya tenemos a la vuelta de la esquina una nueva edici\u00f3n de Fen\u00e1utica, que se celebrar\u00e1 el primer fin de semana de junio en Marina del Sur, el puerto de Las Galletas. Ser\u00e1 los d\u00edas 2 y 3 de junio.<em>\u00a0<\/em>El evento, una gran fiesta del mar , engloba una feria n\u00e1utica, diversas competiciones deportivas ( la sexta edici\u00f3n de la regata Guanche&#8217;s Cup y el XX Campeonato de Video Submarino de Canarias) y mas de 40 actividades de tem\u00e1tica na\u00fatica y deportiva pero tambi\u00e9n gastronom\u00eda, m\u00fasica , shows , exhibiciones y talleres.<\/p>\n<p>Este a\u00f1o , la feria n\u00e1utica se ha consolidado como la \u00fanica de Tenerife y la mas popular de Canarias celebrada en una marina deportiva.<br \/>\nLa gran fiesta del mar, que en 2017 recibi\u00f3 a m\u00e1s de 12.500 personas, acoger\u00e1 la sexta edici\u00f3n de la regata Guanche\u2019s Cup, organizada por el Real Club N\u00e1utico de Tenerife, tanto en la modalidad de vela ligera Optimist y L\u00e1ser como en la de Crucero.<\/p>\n<p>Adem\u00e1s, por primera vez, Fen\u00e1utica celebrar\u00e1 el XX Campeonato de Canarias de V\u00eddeo Submarino, organizado por la Federaci\u00f3n de Canarias de Actividades Subacu\u00e1ticas (FEDECAS). Asimismo, la exposici\u00f3n del 50 aniversario de FEDAS se presenta como una novedad dentro de la agenda de Fen\u00e1utica 2018. Se trata de una muestra fotogr\u00e1fica que ha estado presente en el Real Club N\u00e1utico de Palma de Mallorca, y de la que podr\u00e1n disfrutar todos los visitantes de forma gratuita.<\/p>\n<p>Y es que, en paralelo a las competiciones, la Feria N\u00e1utica de Canarias organizar\u00e1 una amplia variedad de actividades como buceo, buceo adaptado (para personas con discapacidad)apnea, kayak, paddle surf, vela, motos acu\u00e1ticas, surf, kite surf, excursiones en barco o avistamientos de cet\u00e1ceos. Tambi\u00e9n habr\u00e1 talleres infantiles y actividades relacionadas con el cuidado de nuestros mares. Actividades pioneras y originarias de Fen\u00e1utica como el barco que traslada visitantes desde el puerto de Los Cristianos a Marina del Sur, el puerto de Las Galletas, el bodypaint marino (el cartel de este a\u00f1o refleja el realizado el a\u00f1o pasado por la artista Karol Karoline) y la batucada inaugural seguir\u00e1n teniendo cabida en este popular evento. Una suelta de tortugas a bordo, a cargo de Turismo de Tenerife, ser\u00e1 de nuevo una de las acciones estrella de este a\u00f1o. Las actividades son en su mayor parte gratuitas y algunas tendr\u00e1n un precio simb\u00f3lico.<\/p>\n<p>La parte m\u00fasical cobra gran importancia en Fen\u00e1utica 2018 , d\u00f3nde el Hard Rock Hotel Tenerife se har\u00e1 cargo del show inaugural . Adem\u00e1s de la batucada, s\u00edmbolo inequ\u00edvoco de que Fen\u00e1utica est\u00e1 en marcha, la actuaci\u00f3n de un dj y varios conciertos (a cargo de Ni 1 pelo de tonto y Barman Flax) tendr\u00e1n lugar durante los dos d\u00edas de celebraci\u00f3n del evento. La gastronom\u00eda , tambi\u00e9n cobra relevancia en Fen\u00e1utica, d\u00f3nde varios restauradores de la zona mostrar\u00e1n sus especialidades junto con los mas de diez bares y restaurantes ubicados en la marina. Tambi\u00e9n habr\u00e1 lugar para un rincon d\u00f3nde artesanos de la isla mostrar\u00e1n sus productos.<\/p>\n<p>Nos queda dar nuestros mas sinceros agradecimientos a patrocinadores tan importantes como el Patronato de Turismo del Ayuntamiento de Arona, as\u00ed como a las \u00e1reas de Deportes y Promoci\u00f3n Econ\u00f3mica del Ayuntamiento , al Cabildo , con Deportes y Turismo de Tenerife, el \u00e1rea de Turismo de Costa Adeje , Asn\u00e1utica y a empresas privadas tan importantes como Binter Canarias, Aequor Spa, Puerto Mog\u00e1n, Marina Rubic\u00f3n y Hard Rock Hotel Tenerife.<\/p>\n<p>Con estas pinceladas que les presentamos , s\u00f3lo nos queda convocarles en Marina del Sur, el puerto de Las Galletas, los pr\u00f3ximos 2 y 3 de Junio , d\u00f3nde visitantes de todas las edades y condici\u00f3n disfrutar\u00e1n de dos d\u00edas llenos de mar, n\u00e1utica, ocio y mucha diversi\u00f3n.<\/p>\n<p>M\u00e1s informaci\u00f3n en: <a href=\"http:\/\/www.fenautica.com\">www.fenautica.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya tenemos a la vuelta de la esquina una nueva edici\u00f3n de Fen\u00e1utica, que se celebrar\u00e1 el primer fin de semana de junio en Marina del Sur, el puerto de Las Galletas<\/p>\n","protected":false},"author":18,"featured_media":14711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1453],"class_list":["post-14697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacamos","tag-fenautica","last_archivepost"],"_links":{"self":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/14697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/comments?post=14697"}],"version-history":[{"count":3,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/14697\/revisions"}],"predecessor-version":[{"id":14712,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/posts\/14697\/revisions\/14712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media\/14711"}],"wp:attachment":[{"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/media?parent=14697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/categories?post=14697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webtenerife.com\/blogcorporativo\/wp-json\/wp\/v2\/tags?post=14697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}